{"id":29,"count":4,"description":"","link":"https:\/\/dideesmagazine.com\/uk\/category\/wellness\/mindful-living\/","name":"Mindful Living","slug":"mindful-living","taxonomy":"category","parent":28,"meta":[],"_links":{"self":[{"href":"https:\/\/dideesmagazine.com\/uk\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dideesmagazine.com\/uk\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dideesmagazine.com\/uk\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/dideesmagazine.com\/uk\/wp-json\/wp\/v2\/categories\/28"}],"wp:post_type":[{"href":"https:\/\/dideesmagazine.com\/uk\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}